{"id":5757,"date":"2023-12-19T11:54:21","date_gmt":"2023-12-19T18:54:21","guid":{"rendered":"https:\/\/www.bentleymore.com\/?p=5757"},"modified":"2026-05-05T01:38:38","modified_gmt":"2026-05-05T08:38:38","slug":"que-no-debo-decirle-a-mi-compania-de-seguros-despues-de-un-accidente","status":"publish","type":"post","link":"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/","title":{"rendered":"\u00bfQu\u00e9 no debo decirle a mi compa\u00f1\u00eda de seguros despu\u00e9s de un accidente?"},"content":{"rendered":"<p>Las compa\u00f1\u00edas de seguros hacen que lidiar con un accidente automovil\u00edstico resulte abrumador. Aunque debes informar del incidente a tu aseguradora, evita hacer declaraciones concretas para no perjudicar tu reclamaci\u00f3n ni que se reduzca la indemnizaci\u00f3n.<\/p>\n<p>Para proteger sus intereses, busque la representaci\u00f3n de un abogado con experiencia <strong><a href=\"https:\/\/www.bentleymore.com\/es\/abogado-especializado-en-accidentes-automovilisticos-en-riverside\/\">Riverside: Abogado especializado en accidentes automovil\u00edsticos<\/a><\/strong> antes de iniciar las negociaciones con las compa\u00f1\u00edas de seguros. Estos profesionales del derecho pueden velar por tus derechos desde la primera conversaci\u00f3n hasta la resoluci\u00f3n de tu caso, ya sea mediante un acuerdo negociado o un juicio.<\/p>\n<p style=\"text-align: center;\"><a class=\"onsite-btn\" href=\"https:\/\/www.bentleymore.com\/es\/contactenos\/\" target=\"_self\" rel=\"noopener nofollow\">Programe una consulta inicial gratuita<\/a><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-transparent ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Mostrar\/ocultar \u00edndice\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Alternar<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#what-to-avoid-disclosing-to-your-insurance-company-after-an-accident\" >Qu\u00e9 debes evitar revelar a tu compa\u00f1\u00eda de seguros despu\u00e9s de un accidente<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#admitting-responsibility-for-the-incident\" >Asumir la responsabilidad por el incidente<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#admitting-to-the-use-of-mind-altering-substances-before-the-crash\" >Admitir el consumo de sustancias que alteran la mente antes del accidente<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#dont-give-your-personal-opinion\" >No des tu opini\u00f3n personal<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#downplaying-injury-severity\" >Minimizar la gravedad de una lesi\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#dont-exaggerate-your-injuries\" >No exageres tus lesiones<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#speculating-the-future-of-your-injuries\" >Reflexiones sobre el futuro de tus lesiones<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#offering-irrelevant-details\" >Proporcionar detalles irrelevantes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#sharing-names\" >Nombres compartidos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#revealing-you-dont-have-legal-representation-yet\" >Indicar que a\u00fan no cuenta con representaci\u00f3n legal<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#agreeing-to-recorded-statements\" >Aceptaci\u00f3n de las declaraciones grabadas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#agreeing-to-an-early-settlement\" >Aceptar un acuerdo anticipado<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#other-steps-you-can-take-to-protect-your-claim\" >Otras medidas que puede tomar para proteger su reclamaci\u00f3n<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#seek-medical-treatment-promptly\" >Busque atenci\u00f3n m\u00e9dica de inmediato<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#report-the-incident-to-local-law-enforcement\" >Denuncie el incidente a las autoridades locales<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#recognize-the-potential-time-constraints-on-your-legal-rights\" >Ten en cuenta los posibles plazos que afectan a tus derechos legales<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#maintain-records-and-documentation\" >Llevar registros y documentaci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#limit-social-media-use\" >Limita el uso de las redes sociales<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#dont-handle-your-injury-case-alone\" >No se encargue solo de su caso de lesiones<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#contact-an-experienced-accident-attorney-today-for-help\" >P\u00f3ngase en contacto hoy mismo con un abogado con experiencia en accidentes para obtener ayuda<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"what-to-avoid-disclosing-to-your-insurance-company-after-an-accident\"><\/span>Qu\u00e9 debes evitar revelar a tu compa\u00f1\u00eda de seguros despu\u00e9s de un accidente<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-5758\" src=\"https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/What-Should-I-Not-Tell-My-Insurance-Company-After-an-Accident.jpg\" alt=\"\u00bfQu\u00e9 no debo decirle a mi compa\u00f1\u00eda de seguros despu\u00e9s de un accidente?\" width=\"350\" height=\"233\" srcset=\"https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/What-Should-I-Not-Tell-My-Insurance-Company-After-an-Accident.jpg 1000w, https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/What-Should-I-Not-Tell-My-Insurance-Company-After-an-Accident-300x200.jpg 300w, https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/What-Should-I-Not-Tell-My-Insurance-Company-After-an-Accident-768x512.jpg 768w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/p>\n<p>Recuerda lo que no debes revelar a tu compa\u00f1\u00eda de seguros tras un accidente para proteger tus derechos y garantizar un resultado justo.<\/p>\n<p>Estos son los puntos clave que conviene evitar compartir:<\/p>\n<h3><span class=\"ez-toc-section\" id=\"admitting-responsibility-for-the-incident\"><\/span>Asumir la responsabilidad por el incidente<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Evita <strong>reconocer la culpa<\/strong> por el accidente, incluso en <strong>estados con responsabilidad objetiva<\/strong>. Reconocer la culpa puede acarrear consecuencias negativas, como la denegaci\u00f3n de la reclamaci\u00f3n, <strong><a href=\"https:\/\/www.bentleymore.com\/es\/blog\/minimizar-las-reclamaciones-por-accidentes-de-trafico\/\">remuneraci\u00f3n insuficiente<\/a><\/strong>, y la aseguradora que impugna su caso.<\/p>\n<p>Evita hacer este tipo de declaraciones, a pesar de la tendencia natural a expresar arrepentimiento o admitir la culpa, ya que las compa\u00f1\u00edas de seguros dan prioridad a sus ganancias y podr\u00edan utilizar cualquier admisi\u00f3n en tu contra.<\/p>\n<p><a href=\"https:\/\/www.bentleymore.com\/es\/blog\/que-hacer-despues-de-un-accidente-de-trafico\/\"><strong>Despu\u00e9s de un accidente<\/strong><\/a>, es normal sentirse conmocionado y alterado. Sin embargo, evite pedir disculpas, incluso si sospecha que tiene parte de la culpa. Un \u201clo siento\u201d puede malinterpretarse como una admisi\u00f3n de culpa, lo que podr\u00eda perjudicar su reclamaci\u00f3n. Deje que las autoridades y las compa\u00f1\u00edas de seguros involucradas <strong>determinar la culpa<\/strong> basado en <a href=\"https:\/\/www.bentleymore.com\/es\/blog\/que-pruebas-podrian-ayudar-en-mi-caso-de-accidente-automovilistico\/\"><strong>pruebas<\/strong><\/a> y datos.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"admitting-to-the-use-of-mind-altering-substances-before-the-crash\"><\/span>Admitir el consumo de sustancias que alteran la mente antes del accidente<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>No mencione ninguna sustancia que pueda alterar el estado mental que haya consumido antes del accidente, como alcohol o medicamentos, aunque los haya tomado varias horas antes del accidente.<\/p>\n<p>Conducir bajo los efectos del alcohol o las drogas es ilegal en todo el mundo, y hacer referencia a un estado de embriaguez anterior al accidente, aunque sea legalmente admisible, podr\u00eda dar a la aseguradora motivos para rechazar tu reclamaci\u00f3n.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"dont-give-your-personal-opinion\"><\/span>No des tu opini\u00f3n personal<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Act\u00fae con cautela al expresar opiniones personales sobre la culpa. Independientemente de su grado de certeza, las opiniones personales sobre la culpa son intr\u00ednsecamente subjetivas. Las declaraciones en las que se atribuye la culpa, aunque sean v\u00e1lidas, pueden debilitar la solidez de su caso.<\/p>\n<p>Act\u00fae con cautela y evite expresar opiniones a menos que pueda respaldarlas con pruebas concretas. Su funci\u00f3n consiste en proporcionar informaci\u00f3n objetiva sobre el accidente y su experiencia, dejando la determinaci\u00f3n de la responsabilidad en manos de los profesionales del derecho.<\/p>\n<p>Su abogado puede orientarle para que pueda lidiar con este aspecto de su caso.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"downplaying-injury-severity\"><\/span>Minimizar la gravedad de una lesi\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Cuando hable de sus lesiones con la compa\u00f1\u00eda de seguros, evite la tentaci\u00f3n de restar importancia a su gravedad. Aunque minimizar las molestias pueda parecer lo correcto y una muestra de cortes\u00eda, las lesiones pueden agravarse con el tiempo, y lo que parecen problemas menores pueden convertirse en graves problemas m\u00e9dicos.<\/p>\n<p>Subestimar tus lesiones puede dar lugar a que la aseguradora <strong><a href=\"https:\/\/www.bentleymore.com\/es\/blog\/por-que-las-companias-de-seguros-ofrecen-indemnizaciones-bajas\/\">ofrecer un acuerdo insuficiente<\/a><\/strong> para cubrir los gastos m\u00e9dicos y la atenci\u00f3n relacionada. Describa detalladamente sus s\u00edntomas.<\/p>\n<p>Para garantizar una evaluaci\u00f3n precisa de su situaci\u00f3n, evite decir que se siente bien o que cree que no tiene lesiones.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"dont-exaggerate-your-injuries\"><\/span>No exageres tus lesiones<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Por otro lado, evite exagerar o adornar la gravedad de sus lesiones o los da\u00f1os sufridos. Si bien es fundamental ser honesto respecto a sus lesiones, exagerar puede resultar contraproducente, ya que los ajustadores de seguros son expertos en detectar inconsistencias.<\/p>\n<p>La exageraci\u00f3n puede poner en riesgo tu credibilidad y debilitar tu caso en general. Lim\u00edtate a proporcionar informaci\u00f3n veraz y precisa para reforzar tu posici\u00f3n en el proceso de reclamaci\u00f3n y recibir la indemnizaci\u00f3n que te corresponde por tu <a href=\"https:\/\/www.law.cornell.edu\/wex\/damages\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">da\u00f1os<\/a>.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"speculating-the-future-of-your-injuries\"><\/span>Reflexiones sobre el futuro de tus lesiones<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Cuando hable de sus lesiones con la compa\u00f1\u00eda de seguros, evite especular sobre posibles problemas de salud o complicaciones futuras. Lim\u00edtese a los datos concretos de sus lesiones actuales, tal y como las han diagnosticado los profesionales m\u00e9dicos.<\/p>\n<p>Si se dedica a la especulaci\u00f3n, la compa\u00f1\u00eda de seguros podr\u00eda tener motivos para rechazar su reclamaci\u00f3n o poner en duda su honestidad.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"offering-irrelevant-details\"><\/span>Proporcionar detalles irrelevantes<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Del mismo modo, cuando describas los detalles del accidente a tu compa\u00f1\u00eda de seguros, c\u00e9ntrate en los hechos esenciales y proporciona los detalles pertinentes. A la aseguradora le interesan principalmente las circunstancias del accidente, m\u00e1s que tu historia personal o acontecimientos ajenos al incidente.<\/p>\n<p>Evite hablar de temas que no tengan relaci\u00f3n con el asunto o especular sobre situaciones hipot\u00e9ticas, ya que esto podr\u00eda dar lugar a malentendidos o interpretaciones err\u00f3neas que compliquen su reclamaci\u00f3n.<\/p>\n<p>Aunque expresarte y compartir aspectos personales de tu vida pueda resultarte reconfortante, evita dar detalles excesivos e irrelevantes. Conc\u00e9ntrate en los elementos esenciales del incidente y evita hablar de asuntos que no tengan relaci\u00f3n con \u00e9l, como la familia, el trabajo, accidentes anteriores o lesiones que no est\u00e9n relacionadas con el incidente actual.<\/p>\n<p>Recuerda que un exceso de informaci\u00f3n podr\u00eda perjudicar tu caso, por lo que es fundamental centrarse en los detalles relevantes. Cualquier cosa que digas podr\u00eda utilizarse en tu contra o tergiversarse en beneficio de las compa\u00f1\u00edas de seguros.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"sharing-names\"><\/span>Nombres compartidos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Evita compartir los nombres de familiares, amigos o testigos directamente con la compa\u00f1\u00eda de seguros, ya que esto podr\u00eda no redundar en tu beneficio. Los peritos de seguros pueden ponerse en contacto con estas personas para recabar informaci\u00f3n que contradiga tu versi\u00f3n de los hechos, lo que podr\u00eda debilitar tu posici\u00f3n.<\/p>\n<p>Por otro lado, comparta siempre esos nombres con su abogado, ya que \u00e9l podr\u00e1 evaluar si esas personas poseen pruebas valiosas que respalden su <strong>reclamaci\u00f3n por lesiones<\/strong>. Este enfoque estrat\u00e9gico garantiza que toda la informaci\u00f3n proporcionada se ajuste a su estrategia legal.<\/p>\n<div style=\"background: #f1f1f1; padding: 30px 30px; margin: 30px 0px; border-left: 7px solid #4D6774;\">\n<h3><span class=\"ez-toc-section\" id=\"revealing-you-dont-have-legal-representation-yet\"><\/span>Indicar que a\u00fan no cuenta con representaci\u00f3n legal<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Si a\u00fan no ha contratado a un abogado, tenga mucho cuidado al admitir este hecho ante la compa\u00f1\u00eda de seguros. Las compa\u00f1\u00edas de seguros suelen preferir tratar con personas que no cuentan con representaci\u00f3n legal, ya que pueden recurrir a pr\u00e1cticas cuestionables, ofrecer acuerdos inadecuados u obstaculizar el proceso de reclamaci\u00f3n.<\/p>\n<p>Sin embargo, las aseguradoras abordan con mayor cautela las interacciones con las partes lesionadas que cuentan con asesor\u00eda legal, al reconocer que estas personas son menos vulnerables a la explotaci\u00f3n.<\/p>\n<p>Contar con representaci\u00f3n legal no solo hace que las aseguradoras rindan cuentas, sino que tambi\u00e9n act\u00faa como medida disuasoria contra las conductas poco \u00e9ticas. Lo ideal es que contrates a un abogado con experiencia en accidentes antes de entablar contacto con la compa\u00f1\u00eda de seguros.<\/p>\n<p>Sin embargo, si a\u00fan no lo ha hecho, no indique que no cuenta con representaci\u00f3n legal en este momento. A continuaci\u00f3n, consulte a un abogado lo antes posible para contar con representaci\u00f3n legal.<\/p>\n<\/div>\n<h3><span class=\"ez-toc-section\" id=\"agreeing-to-recorded-statements\"><\/span>Aceptaci\u00f3n de las declaraciones grabadas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Ten cuidado si un perito de seguros te pide que des una declaraci\u00f3n grabada sobre el accidente. Aunque te den a entender que est\u00e1s obligado a hacerlo, consulta con un abogado antes de aceptar.<\/p>\n<p>Aunque, por lo general, debes cooperar con tu compa\u00f1\u00eda de seguros, una declaraci\u00f3n grabada puede entra\u00f1ar riesgos.<\/p>\n<p>Los peritos de seguros pueden hacer preguntas capciosas o intentar pillarte desprevenido, lo que podr\u00eda debilitar tu reclamaci\u00f3n. En muchos casos, no est\u00e1s obligado a prestar declaraci\u00f3n grabada, y contar con un abogado puede proteger tus intereses en estas situaciones.<\/p>\n<p>Supongamos que la compa\u00f1\u00eda de seguros te solicita informaci\u00f3n. En ese caso, pueden ponerse en contacto con tu asesor legal, lo que garantiza la protecci\u00f3n de tus derechos y la integridad de tu reclamaci\u00f3n.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"agreeing-to-an-early-settlement\"><\/span>Aceptar un acuerdo anticipado<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Evite aceptar precipitadamente una oferta inicial de liquidaci\u00f3n por parte de la compa\u00f1\u00eda de seguros, ya que estas ofertas tienen como objetivo resolver r\u00e1pidamente las reclamaciones y minimizar los pagos. Aunque hay casos en los que las aseguradoras gestionan las reclamaciones de forma transparente y ofrecen una indemnizaci\u00f3n justa, lamentablemente estos casos son poco frecuentes.<\/p>\n<p>Tras un accidente, es posible que reciba una oferta de acuerdo anticipado antes de comprender plenamente el valor real de su reclamaci\u00f3n. Aceptar esta oferta sin tener una idea clara del alcance de los da\u00f1os y de c\u00f3mo sus lesiones podr\u00edan afectar su futuro puede acarrearle gastos imprevistos.<\/p>\n<p>Es posible que los acuerdos iniciales no cubran adecuadamente los gastos m\u00e9dicos, los da\u00f1os materiales o las p\u00e9rdidas futuras.<\/p>\n<p>Las compa\u00f1\u00edas de seguros pueden presentar intencionalmente una oferta baja antes de que consultes con un abogado, aprovech\u00e1ndose de tu posible desesperaci\u00f3n y de tu desconocimiento sobre el valor real de tu reclamaci\u00f3n. Consulta siempre a un abogado con experiencia en accidentes antes de aceptar cualquier acuerdo para asegurarte de que sea justo.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"other-steps-you-can-take-to-protect-your-claim\"><\/span>Otras medidas que puede tomar para proteger su reclamaci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-5759\" src=\"https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/Other-Steps-You-Can-Take-to-Protect-Your-Claim.jpg\" alt=\"Otras medidas que puede tomar para proteger su reclamaci\u00f3n\" width=\"350\" height=\"233\" srcset=\"https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/Other-Steps-You-Can-Take-to-Protect-Your-Claim.jpg 1000w, https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/Other-Steps-You-Can-Take-to-Protect-Your-Claim-300x200.jpg 300w, https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/Other-Steps-You-Can-Take-to-Protect-Your-Claim-768x512.jpg 768w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/p>\n<p>Adem\u00e1s de evitar revelar demasiada informaci\u00f3n a la compa\u00f1\u00eda de seguros tras un accidente, debes tener cuidado con lo que hagas en los d\u00edas, semanas y meses posteriores.<\/p>\n<p>Aqu\u00ed hay varios <strong>medidas que se deben tomar <\/strong>para proteger tus derechos legales tras un accidente con lesiones.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"seek-medical-treatment-promptly\"><\/span>Busque atenci\u00f3n m\u00e9dica de inmediato<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Buscar atenci\u00f3n m\u00e9dica inmediata es una de las medidas m\u00e1s importantes que se deben tomar tras un accidente. Esto no solo da prioridad a tu bienestar, sino que tambi\u00e9n demuestra tu compromiso con una recuperaci\u00f3n completa.<\/p>\n<p>Descuidar la atenci\u00f3n m\u00e9dica o interrumpir el tratamiento antes de tiempo puede generar inquietudes en las aseguradoras, lo que podr\u00eda dar lugar a la desestimaci\u00f3n de la reclamaci\u00f3n o a una oferta de indemnizaci\u00f3n injusta.<\/p>\n<p>Documentar tu proceso de atenci\u00f3n m\u00e9dica proporciona pruebas valiosas de tus lesiones y del proceso de recuperaci\u00f3n, lo que refuerza la solidez de tu reclamaci\u00f3n.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"report-the-incident-to-local-law-enforcement\"><\/span>Denuncie el incidente a las autoridades locales<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Tambi\u00e9n debe informar de inmediato del accidente a las autoridades policiales, especialmente en los casos en que haya heridos. A menudo es obligatorio notificar la colisi\u00f3n a las autoridades policiales, y el incumplimiento de esta obligaci\u00f3n puede acarrear consecuencias legales, entre ellas posibles cargos por darse a la fuga.<\/p>\n<p>Si no se notifica a las autoridades, se podr\u00eda poner en duda la credibilidad de su denuncia. El <strong><a href=\"https:\/\/www.bentleymore.com\/es\/blog\/que-ocurre-tras-un-accidente-de-trafico-sin-denuncia-policial\/\">informe policial<\/a><\/strong>, una prueba fundamental, aporta detalles importantes sobre el accidente, entre ellos las partes implicadas y la hora en que ocurri\u00f3 el incidente.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"recognize-the-potential-time-constraints-on-your-legal-rights\"><\/span>Ten en cuenta los posibles plazos que afectan a tus derechos legales<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Tras las lesiones sufridas en un accidente, es probable que tengas muchas preocupaciones que ocupan tu mente y tu lista de tareas pendientes, pero no pierdas tiempo a la hora de reclamar una indemnizaci\u00f3n.<\/p>\n<p>Todos los estados aplican un plazo de prescripci\u00f3n para las demandas por da\u00f1os personales, que es un plazo legal estricto dentro del cual las partes perjudicadas deben iniciar una <strong>demanda<\/strong> contra la parte responsable de sus lesiones.<\/p>\n<p>Si no presenta su reclamaci\u00f3n dentro del plazo establecido, no podr\u00e1 reclamar una indemnizaci\u00f3n por sus lesiones. La duraci\u00f3n de este plazo var\u00eda seg\u00fan el estado. Incluso puede variar en funci\u00f3n de la naturaleza y las circunstancias espec\u00edficas de su accidente.<\/p>\n<p>Por ejemplo, el <a href=\"https:\/\/www.law.cornell.edu\/wex\/statute_of_limitations\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">plazo de prescripci\u00f3n<\/a> El plazo de prescripci\u00f3n para las demandas contra el gobierno suele ser m\u00e1s corto que el de otras demandas. Por el contrario, si la demanda se refiere a lesiones sufridas por un menor, el plazo de prescripci\u00f3n suele ampliarse, ya que se suspende hasta que el menor cumpla 18 a\u00f1os.<\/p>\n<p>Tu abogado se asegurar\u00e1 de que no pierdas tu derecho a reclamar la indemnizaci\u00f3n que te corresponde por no respetar estos plazos legales.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"maintain-records-and-documentation\"><\/span>Llevar registros y documentaci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Llevar un registro minucioso es fundamental para respaldar su caso. Mantenga un registro detallado de todas las comunicaciones relacionadas con el accidente, incluidas las conversaciones con los representantes de las aseguradoras, los profesionales m\u00e9dicos y las dem\u00e1s partes involucradas.<\/p>\n<p>Guarde copias de las facturas m\u00e9dicas, los recibos, los presupuestos de reparaci\u00f3n y cualquier otro documento relevante. Compartir toda esta documentaci\u00f3n con su abogado puede reforzar considerablemente las pruebas de su reclamaci\u00f3n.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"limit-social-media-use\"><\/span>Limita el uso de las redes sociales<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Ten cuidado al compartir informaci\u00f3n en l\u00ednea, especialmente en <strong>redes sociales<\/strong> o en otras plataformas p\u00fablicas. Los peritos de seguros pueden analizar minuciosamente tu presencia en l\u00ednea y utilizar el contenido que compartes para rebatir tu caso. Unas fotos aparentemente inocentes de eventos sociales podr\u00edan dar a entender que tus lesiones son menos graves de lo que afirmas.<\/p>\n<p>Aunque quiz\u00e1 no sea necesario dejar de usar las redes sociales por completo, piensa bien qu\u00e9 informaci\u00f3n compartes. Habla con tu abogado sobre tus publicaciones en las redes sociales para decidir cu\u00e1l es la mejor forma de usarlas despu\u00e9s de un accidente con lesiones.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"dont-handle-your-injury-case-alone\"><\/span>No se encargue solo de su caso de lesiones<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Tener que lidiar con las complejidades de un caso legal tras el desgaste f\u00edsico y emocional que supone un accidente no deber\u00eda suponer una carga adicional. En su lugar, conf\u00ede su reclamaci\u00f3n a un abogado especializado en accidentes.<\/p>\n<p>Gracias a sus conocimientos y experiencia, pueden manejar con destreza las complejidades de su caso, gestionar la comunicaci\u00f3n con la compa\u00f1\u00eda de seguros y defender en\u00e9rgicamente sus derechos de indemnizaci\u00f3n. Esto le libera del estr\u00e9s que supone lidiar con asuntos legales, permiti\u00e9ndole centrarse en recuperarse de sus lesiones.<\/p>\n<p>Actuar con discreci\u00f3n tras un accidente es fundamental para preservar la validez de tu reclamaci\u00f3n por accidente. Es esencial que seas consciente de la informaci\u00f3n que compartes y que selecciones cuidadosamente a qui\u00e9n se la revelas.<\/p>\n<p>Recibir atenci\u00f3n m\u00e9dica de inmediato contribuye a su recuperaci\u00f3n y refuerza los fundamentos de su reclamaci\u00f3n. Cumplir con la obligaci\u00f3n de informar del accidente a las autoridades garantiza la disponibilidad de un relato completo y fidedigno del incidente.<\/p>\n<p>Por \u00faltimo, confiar su caso legal a un abogado con experiencia le permite concentrarse en su recuperaci\u00f3n, al tiempo que garantiza la indemnizaci\u00f3n que le corresponde por derecho.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"contact-an-experienced-accident-attorney-today-for-help\"><\/span>P\u00f3ngase en contacto hoy mismo con un abogado con experiencia en accidentes para obtener ayuda<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div id=\"attachment_5675\" style=\"width: 230px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5675\" class=\"wp-image-5675\" src=\"https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/RRGPhotography-5125-1-1-300x287-1.jpg\" alt=\"Greg Bentley y Keith More, abogados especializados en accidentes automovil\u00edsticos\" width=\"220\" height=\"210\" \/><p id=\"caption-attachment-5675\" class=\"wp-caption-text\"><strong><a href=\"https:\/\/www.bentleymore.com\/es\/greg-bentley\/\" rel=\"noreferrer noopener nofollow\">Greg Bentley<\/a> &amp; <a href=\"https:\/\/www.bentleymore.com\/es\/keith-more\/\" rel=\"noreferrer noopener nofollow\">Keith More<\/a> , Abogado especializado en accidentes de tr\u00e1fico en Riverside<\/strong><\/p><\/div>\n<p>Es fundamental actuar con cautela y tomar decisiones informadas al tratar con las compa\u00f1\u00edas de seguros tras un accidente. Aunque es necesario que te comuniques con tu aseguradora, tener cuidado con lo que dices protege tus derechos y preserva el valor de tu reclamaci\u00f3n.<\/p>\n<p>Un experimentado <a href=\"https:\/\/www.bentleymore.com\/es\/abogados-especializados-en-lesiones-personales-en-riverside\/\"><strong>Riverside, abogado especializado en lesiones personales<\/strong><\/a> puede ofrecerle una orientaci\u00f3n muy valiosa, encarg\u00e1ndose de las comunicaciones con las compa\u00f1\u00edas de seguros pertinentes para garantizar que reciba la indemnizaci\u00f3n que le corresponde por derecho. P\u00f3ngase en contacto hoy mismo con un abogado con experiencia en accidentes para iniciar su reclamaci\u00f3n y proteger sus derechos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Insurance companies make dealing with a car accident daunting. While you must report the incident to your insurance provider, avoid specific statements to prevent potential harm to your claim or a reduction in compensation. To protect your interests, seek representation from an experienced Riverside car accident attorney before initiating discussions with insurance companies. These legal&#8230; <a href=\"https:\/\/www.bentleymore.com\/es\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":7,"featured_media":5758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-5757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-car-accident"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>What Should I Not Tell My Insurance Company After an Accident<\/title>\n<meta name=\"description\" content=\"Dealing with insurance companies post-accident? Learn the critical statements to avoid for safeguarding your claim&#039;s value.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bentleymore.com\/es\/blog\/que-no-debo-decirle-a-mi-compania-de-seguros-despues-de-un-accidente\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What Should I Not Tell My Insurance Company After an Accident? | Bentley &amp; More LLP\" \/>\n<meta property=\"og:description\" content=\"Dealing with insurance companies post-accident? Learn the critical statements to avoid for safeguarding your claim&#039;s value.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bentleymore.com\/es\/blog\/que-no-debo-decirle-a-mi-compania-de-seguros-despues-de-un-accidente\/\" \/>\n<meta property=\"og:site_name\" content=\"Bentley &amp; More LLP\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BentleyMoreLLP\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.linkedin.com\/in\/greg-bentley-933389134\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-19T18:54:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T08:38:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/What-Should-I-Not-Tell-My-Insurance-Company-After-an-Accident.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Greg Bentley\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/dailyjournal.com\/article\/382055-greg-bentley\" \/>\n<meta name=\"twitter:site\" content=\"@bentleymore\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Greg Bentley\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/blog\\\/what-should-i-not-tell-my-insurance-company-after-an-accident\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/blog\\\/what-should-i-not-tell-my-insurance-company-after-an-accident\\\/\"},\"author\":{\"name\":\"Greg Bentley\",\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/#\\\/schema\\\/person\\\/3cb7ac5a3abdda65b35ee1e1d295dc4f\"},\"headline\":\"What Should I Not Tell My Insurance Company After an Accident?\",\"datePublished\":\"2023-12-19T18:54:21+00:00\",\"dateModified\":\"2026-05-05T08:38:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/blog\\\/what-should-i-not-tell-my-insurance-company-after-an-accident\\\/\"},\"wordCount\":2034,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/blog\\\/what-should-i-not-tell-my-insurance-company-after-an-accident\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bentleymore.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/What-Should-I-Not-Tell-My-Insurance-Company-After-an-Accident.jpg\",\"articleSection\":[\"Car Accidents\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.bentleymore.com\\\/blog\\\/what-should-i-not-tell-my-insurance-company-after-an-accident\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/blog\\\/what-should-i-not-tell-my-insurance-company-after-an-accident\\\/\",\"url\":\"https:\\\/\\\/www.bentleymore.com\\\/blog\\\/what-should-i-not-tell-my-insurance-company-after-an-accident\\\/\",\"name\":\"What Should I Not Tell My Insurance Company After an Accident\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/blog\\\/what-should-i-not-tell-my-insurance-company-after-an-accident\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/blog\\\/what-should-i-not-tell-my-insurance-company-after-an-accident\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bentleymore.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/What-Should-I-Not-Tell-My-Insurance-Company-After-an-Accident.jpg\",\"datePublished\":\"2023-12-19T18:54:21+00:00\",\"dateModified\":\"2026-05-05T08:38:38+00:00\",\"description\":\"Dealing with insurance companies post-accident? Learn the critical statements to avoid for safeguarding your claim's value.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/blog\\\/what-should-i-not-tell-my-insurance-company-after-an-accident\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bentleymore.com\\\/blog\\\/what-should-i-not-tell-my-insurance-company-after-an-accident\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/blog\\\/what-should-i-not-tell-my-insurance-company-after-an-accident\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bentleymore.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/What-Should-I-Not-Tell-My-Insurance-Company-After-an-Accident.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bentleymore.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/What-Should-I-Not-Tell-My-Insurance-Company-After-an-Accident.jpg\",\"width\":1000,\"height\":667,\"caption\":\"What Should I Not Tell My Insurance Company After an Accident\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/blog\\\/what-should-i-not-tell-my-insurance-company-after-an-accident\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bentleymore.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What Should I Not Tell My Insurance Company After an Accident?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/#website\",\"url\":\"https:\\\/\\\/www.bentleymore.com\\\/\",\"name\":\"Bentley & More LLP\",\"description\":\"Real Trial Lawyers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/#organization\"},\"alternateName\":\"Bentley & More\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bentleymore.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/#organization\",\"name\":\"Bentley & More LLP\",\"alternateName\":\"Bentley & More\",\"url\":\"https:\\\/\\\/www.bentleymore.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bentleymore.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.bentleymore.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo.png\",\"width\":462,\"height\":109,\"caption\":\"Bentley & More LLP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BentleyMoreLLP\\\/\",\"https:\\\/\\\/x.com\\\/bentleymore\",\"https:\\\/\\\/www.instagram.com\\\/bentleyandmorellp\\\/\",\"https:\\\/\\\/www.yelp.com\\\/biz\\\/bentley-and-more-irvine\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bentley-&-more-llp\\\/\",\"https:\\\/\\\/maps.app.goo.gl\\\/RZrMqUo474ugpWBRA\",\"https:\\\/\\\/www.bestlawyers.com\\\/firms\\\/bentley-more-llp\\\/75461\\\/US\",\"https:\\\/\\\/www.orangecountylawyers.com\\\/attorneys\\\/bentley-more-llp\\\/\",\"https:\\\/\\\/profiles.superlawyers.com\\\/california\\\/newport-beach\\\/lawfirm\\\/bentley-and-more-llp\\\/ce1e2f49-0a84-468f-bc17-eade2a364682.html\",\"https:\\\/\\\/uphelp.org\\\/sponsors\\\/bentley-more-llp\\\/\",\"https:\\\/\\\/law.usnews.com\\\/law-firms\\\/bentley-&-more-llp-160536\",\"https:\\\/\\\/www.martindale.com\\\/organization\\\/bentley-more-llp-158828293\\\/newport-beach-california-161028413-f\\\/\",\"https:\\\/\\\/lawyers.findlaw.com\\\/profile\\\/lawfirm\\\/bentley--more-llp\\\/ca\\\/newport-beach\\\/NTAwMzkxM18x\",\"https:\\\/\\\/www.bestlawfirms.com\\\/firms\\\/bentley-more-llp\\\/75461\\\/US\",\"https:\\\/\\\/natlawreview.com\\\/organization\\\/bentley-more-llp\",\"https:\\\/\\\/bentley-more-llp.wheree.com\\\/\",\"https:\\\/\\\/www.callupcontact.com\\\/b\\\/businessprofile\\\/Bentley_amp_More_LLP\\\/9968345\"],\"telephone\":\"+19498703800\",\"legalName\":\"Bentley & More LLP\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bentleymore.com\\\/#\\\/schema\\\/person\\\/3cb7ac5a3abdda65b35ee1e1d295dc4f\",\"name\":\"Greg Bentley\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c7d4c2dc2d793f0cf573fd54a78a4d9023f94f8738a82658f71664a87774f3e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c7d4c2dc2d793f0cf573fd54a78a4d9023f94f8738a82658f71664a87774f3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c7d4c2dc2d793f0cf573fd54a78a4d9023f94f8738a82658f71664a87774f3e?s=96&d=mm&r=g\",\"caption\":\"Greg Bentley\"},\"description\":\"Greg Bentley is Co-Founder of Bentley &amp; More LLP in Newport Beach, California. With 36 years of experience, he represents plaintiffs in personal injury, wrongful death, product liability, insurance bad faith, dangerous road and property conditions, and construction-site failure cases. Admitted to the State Bar of California, Greg earned his J.D. from Western State University College of Law in 1990. He is a member of several invitation-only trial organizations, including the American College of Trial Lawyers and the International Academy of Trial Lawyers, and is active in multiple statewide and regional trial lawyer associations.\",\"sameAs\":[\"https:\\\/\\\/www.bentleymore.com\\\/greg-bentley\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/greg-bentley-933389134\",\"https:\\\/\\\/attorneyatlawmagazine.com\\\/best-attorneys\\\/lawyers\\\/greg-bentley\",\"https:\\\/\\\/www.instagram.com\\\/gregbentleylaw\\\/\",\"https:\\\/\\\/www.advocatemagazine.com\\\/writer\\\/writers\\\/greg-bentley\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/dailyjournal.com\\\/article\\\/382055-greg-bentley\",\"https:\\\/\\\/www.bestlawyers.com\\\/lawyers\\\/gregory-l-greg-bentley\\\/162481\",\"https:\\\/\\\/www.martindale.com\\\/attorney\\\/greg-bentley-168963608\\\/\",\"https:\\\/\\\/plaintiffmagazine.com\\\/authors\\\/item\\\/gregory-l-bentley\",\"https:\\\/\\\/www.facebook.com\\\/greg.bentley.841238\\\/\",\"https:\\\/\\\/apps.calbar.ca.gov\\\/attorney\\\/Licensee\\\/Detail\\\/151147\"],\"honorificPrefix\":\"Mr\",\"gender\":\"male\",\"award\":[\"Named \\\"Lawyer of the Year\\\" by Best Lawyers\u00ae\",\"Recognized in The Best Lawyers in America\u00ae 2026\"],\"knowsAbout\":[\"Personal Injury\",\"Car Accidents\",\"Truck Accidents\",\"Motorcycle Accidents\",\"Wrongful Death\",\"Workers\u2019 Compensation\"],\"knowsLanguage\":[\"English\",\"Spanish\"],\"jobTitle\":\"Co-Founder & Trial Lawyer\",\"worksFor\":\"Bentley & More LLP\",\"url\":\"https:\\\/\\\/www.bentleymore.com\\\/es\\\/blog\\\/author\\\/greg-bentley\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 no debo decirle a mi compa\u00f1\u00eda de seguros despu\u00e9s de un accidente?","description":"\u00bfTienes que lidiar con las compa\u00f1\u00edas de seguros despu\u00e9s de un accidente? Descubre qu\u00e9 comentarios debes evitar para proteger el valor de tu reclamaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bentleymore.com\/es\/blog\/que-no-debo-decirle-a-mi-compania-de-seguros-despues-de-un-accidente\/","og_locale":"es_MX","og_type":"article","og_title":"What Should I Not Tell My Insurance Company After an Accident? | Bentley &amp; More LLP","og_description":"Dealing with insurance companies post-accident? Learn the critical statements to avoid for safeguarding your claim's value.","og_url":"https:\/\/www.bentleymore.com\/es\/blog\/que-no-debo-decirle-a-mi-compania-de-seguros-despues-de-un-accidente\/","og_site_name":"Bentley &amp; More LLP","article_publisher":"https:\/\/www.facebook.com\/BentleyMoreLLP\/","article_author":"https:\/\/www.linkedin.com\/in\/greg-bentley-933389134","article_published_time":"2023-12-19T18:54:21+00:00","article_modified_time":"2026-05-05T08:38:38+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/What-Should-I-Not-Tell-My-Insurance-Company-After-an-Accident.jpg","type":"image\/jpeg"}],"author":"Greg Bentley","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/dailyjournal.com\/article\/382055-greg-bentley","twitter_site":"@bentleymore","twitter_misc":{"Escrito por":"Greg Bentley","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bentleymore.com\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#article","isPartOf":{"@id":"https:\/\/www.bentleymore.com\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/"},"author":{"name":"Greg Bentley","@id":"https:\/\/www.bentleymore.com\/#\/schema\/person\/3cb7ac5a3abdda65b35ee1e1d295dc4f"},"headline":"What Should I Not Tell My Insurance Company After an Accident?","datePublished":"2023-12-19T18:54:21+00:00","dateModified":"2026-05-05T08:38:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bentleymore.com\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/"},"wordCount":2034,"commentCount":0,"publisher":{"@id":"https:\/\/www.bentleymore.com\/#organization"},"image":{"@id":"https:\/\/www.bentleymore.com\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/What-Should-I-Not-Tell-My-Insurance-Company-After-an-Accident.jpg","articleSection":["Car Accidents"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bentleymore.com\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.bentleymore.com\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/","url":"https:\/\/www.bentleymore.com\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/","name":"\u00bfQu\u00e9 no debo decirle a mi compa\u00f1\u00eda de seguros despu\u00e9s de un accidente?","isPartOf":{"@id":"https:\/\/www.bentleymore.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bentleymore.com\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#primaryimage"},"image":{"@id":"https:\/\/www.bentleymore.com\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/What-Should-I-Not-Tell-My-Insurance-Company-After-an-Accident.jpg","datePublished":"2023-12-19T18:54:21+00:00","dateModified":"2026-05-05T08:38:38+00:00","description":"\u00bfTienes que lidiar con las compa\u00f1\u00edas de seguros despu\u00e9s de un accidente? Descubre qu\u00e9 comentarios debes evitar para proteger el valor de tu reclamaci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.bentleymore.com\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bentleymore.com\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bentleymore.com\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#primaryimage","url":"https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/What-Should-I-Not-Tell-My-Insurance-Company-After-an-Accident.jpg","contentUrl":"https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/12\/What-Should-I-Not-Tell-My-Insurance-Company-After-an-Accident.jpg","width":1000,"height":667,"caption":"What Should I Not Tell My Insurance Company After an Accident"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bentleymore.com\/blog\/what-should-i-not-tell-my-insurance-company-after-an-accident\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bentleymore.com\/"},{"@type":"ListItem","position":2,"name":"What Should I Not Tell My Insurance Company After an Accident?"}]},{"@type":"WebSite","@id":"https:\/\/www.bentleymore.com\/#website","url":"https:\/\/www.bentleymore.com\/","name":"Bentley &amp; More LLP","description":"Abogados litigantes de verdad","publisher":{"@id":"https:\/\/www.bentleymore.com\/#organization"},"alternateName":"Bentley & More","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bentleymore.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.bentleymore.com\/#organization","name":"Bentley &amp; More LLP","alternateName":"Bentley & More","url":"https:\/\/www.bentleymore.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bentleymore.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/www.bentleymore.com\/wp-content\/uploads\/2023\/04\/logo.png","width":462,"height":109,"caption":"Bentley & More LLP"},"image":{"@id":"https:\/\/www.bentleymore.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BentleyMoreLLP\/","https:\/\/x.com\/bentleymore","https:\/\/www.instagram.com\/bentleyandmorellp\/","https:\/\/www.yelp.com\/biz\/bentley-and-more-irvine","https:\/\/www.linkedin.com\/company\/bentley-&-more-llp\/","https:\/\/maps.app.goo.gl\/RZrMqUo474ugpWBRA","https:\/\/www.bestlawyers.com\/firms\/bentley-more-llp\/75461\/US","https:\/\/www.orangecountylawyers.com\/attorneys\/bentley-more-llp\/","https:\/\/profiles.superlawyers.com\/california\/newport-beach\/lawfirm\/bentley-and-more-llp\/ce1e2f49-0a84-468f-bc17-eade2a364682.html","https:\/\/uphelp.org\/sponsors\/bentley-more-llp\/","https:\/\/law.usnews.com\/law-firms\/bentley-&-more-llp-160536","https:\/\/www.martindale.com\/organization\/bentley-more-llp-158828293\/newport-beach-california-161028413-f\/","https:\/\/lawyers.findlaw.com\/profile\/lawfirm\/bentley--more-llp\/ca\/newport-beach\/NTAwMzkxM18x","https:\/\/www.bestlawfirms.com\/firms\/bentley-more-llp\/75461\/US","https:\/\/natlawreview.com\/organization\/bentley-more-llp","https:\/\/bentley-more-llp.wheree.com\/","https:\/\/www.callupcontact.com\/b\/businessprofile\/Bentley_amp_More_LLP\/9968345"],"telephone":"+19498703800","legalName":"Bentley & More LLP"},{"@type":"Person","@id":"https:\/\/www.bentleymore.com\/#\/schema\/person\/3cb7ac5a3abdda65b35ee1e1d295dc4f","name":"Greg Bentley","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3c7d4c2dc2d793f0cf573fd54a78a4d9023f94f8738a82658f71664a87774f3e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3c7d4c2dc2d793f0cf573fd54a78a4d9023f94f8738a82658f71664a87774f3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c7d4c2dc2d793f0cf573fd54a78a4d9023f94f8738a82658f71664a87774f3e?s=96&d=mm&r=g","caption":"Greg Bentley"},"description":"Greg Bentley es cofundador de Bentley &amp; More LLP en Newport Beach, California. Con 36 a\u00f1os de experiencia, representa a demandantes en casos de lesiones personales, muerte por negligencia, responsabilidad por productos defectuosos, mala fe de las aseguradoras, condiciones peligrosas en carreteras y propiedades, y defectos en obras de construcci\u00f3n. Habilitado para ejercer en el Colegio de Abogados de California, Greg obtuvo su t\u00edtulo de Doctor en Derecho en la Facultad de Derecho de la Western State University en 1990. Es miembro de varias organizaciones de abogados litigantes a las que solo se puede ingresar por invitaci\u00f3n, entre ellas el Colegio Americano de Abogados Litigantes y la Academia Internacional de Abogados Litigantes, y participa activamente en m\u00faltiples asociaciones de abogados litigantes a nivel estatal y regional.","sameAs":["https:\/\/www.bentleymore.com\/greg-bentley\/","https:\/\/www.linkedin.com\/in\/greg-bentley-933389134","https:\/\/attorneyatlawmagazine.com\/best-attorneys\/lawyers\/greg-bentley","https:\/\/www.instagram.com\/gregbentleylaw\/","https:\/\/www.advocatemagazine.com\/writer\/writers\/greg-bentley","https:\/\/x.com\/https:\/\/dailyjournal.com\/article\/382055-greg-bentley","https:\/\/www.bestlawyers.com\/lawyers\/gregory-l-greg-bentley\/162481","https:\/\/www.martindale.com\/attorney\/greg-bentley-168963608\/","https:\/\/plaintiffmagazine.com\/authors\/item\/gregory-l-bentley","https:\/\/www.facebook.com\/greg.bentley.841238\/","https:\/\/apps.calbar.ca.gov\/attorney\/Licensee\/Detail\/151147"],"honorificPrefix":"Mr","gender":"male","award":["Named \"Lawyer of the Year\" by Best Lawyers\u00ae","Recognized in The Best Lawyers in America\u00ae 2026"],"knowsAbout":["Personal Injury","Car Accidents","Truck Accidents","Motorcycle Accidents","Wrongful Death","Workers\u2019 Compensation"],"knowsLanguage":["English","Spanish"],"jobTitle":"Co-Founder & Trial Lawyer","worksFor":"Bentley & More LLP","url":"https:\/\/www.bentleymore.com\/es\/blog\/author\/greg-bentley\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bentleymore.com\/es\/wp-json\/wp\/v2\/posts\/5757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bentleymore.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bentleymore.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bentleymore.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bentleymore.com\/es\/wp-json\/wp\/v2\/comments?post=5757"}],"version-history":[{"count":1,"href":"https:\/\/www.bentleymore.com\/es\/wp-json\/wp\/v2\/posts\/5757\/revisions"}],"predecessor-version":[{"id":8554,"href":"https:\/\/www.bentleymore.com\/es\/wp-json\/wp\/v2\/posts\/5757\/revisions\/8554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bentleymore.com\/es\/wp-json\/wp\/v2\/media\/5758"}],"wp:attachment":[{"href":"https:\/\/www.bentleymore.com\/es\/wp-json\/wp\/v2\/media?parent=5757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bentleymore.com\/es\/wp-json\/wp\/v2\/categories?post=5757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bentleymore.com\/es\/wp-json\/wp\/v2\/tags?post=5757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}